{"id":29439,"date":"2023-12-22T09:51:44","date_gmt":"2023-12-22T09:51:44","guid":{"rendered":"https:\/\/www.domtar.com\/lavenir-cest-maintenant-celebrons-le-175e-anniversaire-de-domtar-et-regardons-vers-lavenir\/"},"modified":"2023-12-22T09:51:44","modified_gmt":"2023-12-22T09:51:44","slug":"lavenir-cest-maintenant-celebrons-le-175e-anniversaire-de-domtar-et-regardons-vers-lavenir","status":"publish","type":"post","link":"https:\/\/www.domtar.com\/fr\/lavenir-cest-maintenant-celebrons-le-175e-anniversaire-de-domtar-et-regardons-vers-lavenir\/","title":{"rendered":"L&rsquo;avenir, c&rsquo;est maintenant : C\u00e9l\u00e9brons le 175e anniversaire de Domtar et regardons vers l&rsquo;avenir"},"content":{"rendered":"\n<section id=\"immersive_panel_1\" class=\"lc-module section-article-content-block\">\n    <div class=\"lc-module-inner\">\n                <div class=\"article-block-wrapper lc-module-inner fade-bottom\">\n            <div class=\"entry\">\n                <p><span data-contrast=\"auto\">Tout au long de l&rsquo;ann\u00e9e 2023, nous avons comm\u00e9mor\u00e9 le 175<\/span><span data-contrast=\"auto\">anniversaire<\/span><span data-contrast=\"auto\"> anniversaire de Domtar et avons r\u00e9fl\u00e9chi aux nombreuses fa\u00e7ons dont ceux qui nous ont pr\u00e9c\u00e9d\u00e9s ont jet\u00e9 les bases de ce que nous sommes aujourd&rsquo;hui et de ce que nous pouvons devenir \u00e0 l&rsquo;avenir. <\/span> <span data-ccp-props=\"{\"134233279\":true,\"201341983\":0,\"335559739\":0,\"335559740\":240}\"> <\/span><\/p>\n<p><span data-contrast=\"auto\">Notre capacit\u00e9 \u00e0 r\u00e9inventer notre entreprise &#8211; tout en restant attach\u00e9s \u00e0 nos employ\u00e9s, \u00e0 l&rsquo;environnement et aux communaut\u00e9s qui nous entourent &#8211; nous a mis sur la voie d&rsquo;une croissance et d&rsquo;un succ\u00e8s continus. Revenons sur certains des moments cl\u00e9s de nos 175 premi\u00e8res ann\u00e9es, alors que nous nous pr\u00e9parons pour les 175 prochaines. <\/span><span data-ccp-props=\"{\"134233279\":true,\"201341983\":0,\"335559739\":0,\"335559740\":240}\"> <\/span><\/p>\n<h4 style=\"text-align: center;\"><a href=\"https:\/\/www.domtar.com\/wp-content\/uploads\/2023\/12\/Newsroom_Dec2023_175eAnniversaire_FR.pdf\" target=\"_blank\" rel=\"noopener\">Lire l&rsquo;article en fran\u00e7ais (PDF)<\/a><\/h4>\n<h2>R\u00e9invention : Le changement est source d&rsquo;opportunit\u00e9s<\/h2>\n<p><span data-contrast=\"auto\">Rester en activit\u00e9 depuis 1848 n&rsquo;est pas le fruit du hasard. C&rsquo;est le r\u00e9sultat de notre volont\u00e9 de r\u00e9pondre aux besoins de nos clients et de rester un partenaire privil\u00e9gi\u00e9. Au fil des ans, nous avons \u00e9t\u00e9 un fournisseur essentiel pour un ensemble vari\u00e9 d&rsquo;entreprises, fournissant une grande vari\u00e9t\u00e9 de mat\u00e9riaux essentiels au fur et \u00e0 mesure de l&rsquo;\u00e9volution des march\u00e9s.  <\/span><span data-ccp-props=\"{\"134233279\":true,\"201341983\":0,\"335559739\":0,\"335559740\":240}\"> <\/span><\/p>\n<p><span data-contrast=\"auto\">Par exemple, nous sommes entr\u00e9s dans le secteur des mat\u00e9riaux de construction &#8211; y compris les toitures, le pavage et les produits du bois &#8211; pendant le boom de la construction qui a suivi la Premi\u00e8re Guerre mondiale. Plus tard, pendant la Grande D\u00e9pression, notre pr\u00e9d\u00e9cesseur Dominion Tar and Chemical a \u00e9galement acquis une soci\u00e9t\u00e9 qui produisait du sel de marque Sifto. <\/span><span data-ccp-props=\"{\"134233279\":true,\"201341983\":0,\"335559739\":0,\"335559740\":240}\"> <\/span><\/p>\n<h2><span data-contrast=\"auto\">Guid\u00e9s par nos valeurs<\/span><span data-ccp-props=\"{\"134233279\":true,\"201341983\":0,\"335559739\":0,\"335559740\":240}\"> <\/span><\/h2>\n<p><span data-contrast=\"auto\">Au fil de ces changements, nous sommes rest\u00e9s fid\u00e8les \u00e0 nos valeurs, <\/span><a href=\"https:\/\/newsroom.domtar.com\/domtar-anniversary-celebrates-legacy\/\" target=\"_blank\" rel=\"noopener\"><span data-contrast=\"none\">nous sommes rest\u00e9s fid\u00e8les \u00e0 nos valeurs<\/span><\/a><span data-contrast=\"auto\">Nous sommes rest\u00e9s fid\u00e8les \u00e0 nos valeurs, \u00e0 savoir agir avec agilit\u00e9, innovation et bienveillance. <\/span> <span data-ccp-props=\"{\"134233279\":true,\"201341983\":0,\"335559739\":0,\"335559740\":240}\"> <\/span><\/p>\n<p><span data-contrast=\"auto\">Ces valeurs ont \u00e9t\u00e9 d\u00e9montr\u00e9es tout au long de notre histoire, alors que nous cherchions continuellement \u00e0 devenir un meilleur employeur, un meilleur fournisseur et un meilleur voisin.  <\/span><span data-ccp-props=\"{\"134233279\":true,\"201341983\":0,\"335559739\":0,\"335559740\":240}\"> <\/span><\/p>\n<p><span data-contrast=\"auto\">Nos valeurs sont \u00e0 la base des politiques et pratiques de s\u00e9curit\u00e9 que nous avons mises en place aujourd&rsquo;hui et qui sont le r\u00e9sultat de notre travail pour <\/span><a href=\"https:\/\/newsroom.domtar.com\/manufacturing-safety-at-domtar\/\" target=\"_blank\" rel=\"noopener\"><span data-contrast=\"none\">adapter et am\u00e9liorer la mani\u00e8re dont nous assurons la s\u00e9curit\u00e9 des employ\u00e9s sur le lieu de travail<\/span><\/a><span data-contrast=\"auto\">.<\/span><span data-ccp-props=\"{\"134233279\":true,\"201341983\":0,\"335559739\":0,\"335559740\":240}\"> <\/span><\/p>\n<p><span data-contrast=\"auto\">Alors que nous c\u00e9l\u00e9brons le 175e anniversaire de Domtar, nous sommes fiers de la culture positive dont font preuve les nombreux employ\u00e9s qui travaillent avec nous depuis trois, quatre, cinq et m\u00eame six d\u00e9cennies. <\/span><a href=\"https:\/\/newsroom.domtar.com\/long-time-windsor-mill-employee-60-years\/\" target=\"_blank\" rel=\"noopener\"><span data-contrast=\"none\">et m\u00eame six d\u00e9cennies<\/span><\/a><span data-contrast=\"auto\">Nous sommes \u00e9galement fiers du parcours professionnel des <\/span><a href=\"https:\/\/newsroom.domtar.com\/women-of-domtar\/\" target=\"_blank\" rel=\"noopener\"><span data-contrast=\"none\">femmes qui ont contribu\u00e9 \u00e0 red\u00e9finir<\/span><\/a><span data-contrast=\"auto\"> ce \u00e0 quoi ressemble l&rsquo;industrie manufacturi\u00e8re moderne.<\/span><span data-ccp-props=\"{\"134233279\":true,\"201341983\":0,\"335559739\":0,\"335559740\":240}\"> <\/span><\/p>\n<p><a href=\"https:\/\/newsroom.domtar.com\/domtars-sustainability-story\/\" target=\"_blank\" rel=\"noopener\"><span data-contrast=\"none\">Domtar est un leader en mati\u00e8re de d\u00e9veloppement durable<\/span><\/a><span data-contrast=\"auto\">. We were the first forest products company in North America to achieve   <\/span><a href=\"https:\/\/newsroom.domtar.com\/fsc-forest-conversion-policy\/\" target=\"_blank\" rel=\"noopener\"><span data-contrast=\"none\">Forest Stewardship Council (FSC\u00ae)<\/span><\/a><span data-contrast=\"auto\"> Nous avons obtenu la certification FSC\u00ae pour nos terres et nous avons continu\u00e9 \u00e0 entretenir des relations \u00e9troites avec les organisations de protection de l&rsquo;environnement.<\/span><span data-ccp-props=\"{\"134233279\":true,\"201341983\":0,\"335559739\":0,\"335559740\":240}\"> <\/span><\/p>\n<p><span data-contrast=\"auto\">Nous reconnaissons depuis longtemps l&rsquo;importance d&rsquo;investir dans les communaut\u00e9s au sein desquelles nous op\u00e9rons, pour en faire <\/span><a href=\"https:\/\/newsroom.domtar.com\/outdoor-recreation-domtar-legacy\/#lg=1&amp;slide=5\" target=\"_blank\" rel=\"noopener\"><span data-contrast=\"none\">de meilleurs endroits pour vivre, travailler et se divertir<\/span><\/a><span data-contrast=\"auto\">. To help nurture the next generation of talent, we gave a total of $100,000 in scholarships to two local universities. The funds will be awarded to students in engineering, forestry, STEM and education at Clemson University in South Carolina and the Universit\u00e9 de Sherbrooke in Quebec.  <\/span><span data-ccp-props=\"{\"134233279\":true,\"201341983\":0,\"335559739\":0,\"335559740\":240}\"> <\/span><\/p>\n<h2>Le prochain est le pr\u00e9sent<span data-ccp-props=\"{\"134233279\":true,\"201341983\":0,\"335559739\":0,\"335559740\":240}\"> <\/span><\/h2>\n<p><span data-contrast=\"auto\">Nous vivons un moment passionnant de l&rsquo;histoire de Domtar. Alors que nous c\u00e9l\u00e9brons le 175e anniversaire de Domtar, nos yeux sont tourn\u00e9s vers l&rsquo;avenir en tant que membre du groupe d&rsquo;entreprises Paper Excellence. Notre histoire de r\u00e9invention se poursuit.    <\/span><\/p>\n<p>&nbsp;<\/p>\n<h2>Apprenez-en plus sur l&rsquo;histoire de la r\u00e9invention de Domtar :<\/h2>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"5\" data-list-defn-props=\"{\"335552541\":1,\"335559684\":-2,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"1\"><a href=\"https:\/\/newsroom.domtar.com\/domtars-sustainability-story\/\" target=\"_blank\" rel=\"noopener\"><span data-contrast=\"none\">L&rsquo;histoire de la durabilit\u00e9 de Domtar : Une autre raison de c\u00e9l\u00e9brer notre h\u00e9ritage<\/span><\/a> <span data-ccp-props=\"{\"201341983\":0,\"335559739\":0,\"335559740\":240,\"469777462\":[7140],\"469777927\":[0],\"469777928\":[1]}\"> <\/span><\/li>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"5\" data-list-defn-props=\"{\"335552541\":1,\"335559684\":-2,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"2\" data-aria-level=\"1\"><a href=\"https:\/\/newsroom.domtar.com\/women-of-domtar\/\" target=\"_blank\" rel=\"noopener\"><span data-contrast=\"none\">Dans leurs mots : Les femmes de Domtar, hier et aujourd&rsquo;hui<\/span><\/a><span data-ccp-props=\"{\"201341983\":0,\"335559739\":0,\"335559740\":240,\"469777462\":[7140],\"469777927\":[0],\"469777928\":[1]}\"> <\/span><\/li>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"5\" data-list-defn-props=\"{\"335552541\":1,\"335559684\":-2,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"3\" data-aria-level=\"1\"><a href=\"https:\/\/newsroom.domtar.com\/manufacturing-safety-at-domtar\/\" target=\"_blank\" rel=\"noopener\"><span data-contrast=\"none\">L&rsquo;\u00e9volution de la s\u00e9curit\u00e9 de fabrication chez Domtar<\/span><\/a><span data-ccp-props=\"{\"201341983\":0,\"335559739\":0,\"335559740\":240,\"469777462\":[7140],\"469777927\":[0],\"469777928\":[1]}\"> <\/span><\/li>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"5\" data-list-defn-props=\"{\"335552541\":1,\"335559684\":-2,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"4\" data-aria-level=\"1\"><a href=\"https:\/\/newsroom.domtar.com\/outdoor-recreation-domtar-legacy\/\" target=\"_blank\" rel=\"noopener\"><span data-contrast=\"none\">Loisirs de plein air : Une part importante de l&rsquo;h\u00e9ritage de Domtar<\/span><\/a><span data-ccp-props=\"{\"201341983\":0,\"335559739\":0,\"335559740\":240,\"469777462\":[7140],\"469777927\":[0],\"469777928\":[1]}\"> <\/span><\/li>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"5\" data-list-defn-props=\"{\"335552541\":1,\"335559684\":-2,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"5\" data-aria-level=\"1\"><a href=\"https:\/\/newsroom.domtar.com\/long-time-windsor-mill-employee-60-years\/\" target=\"_blank\" rel=\"noopener\"><span data-contrast=\"none\">Un employ\u00e9 de longue date de l&rsquo;usine de Windsor se souvient de ses 60 ans chez Domtar<\/span><\/a><span data-ccp-props=\"{\"201341983\":0,\"335559739\":0,\"335559740\":240,\"469777462\":[7140],\"469777927\":[0],\"469777928\":[1]}\"> <\/span><\/li>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"5\" data-list-defn-props=\"{\"335552541\":1,\"335559684\":-2,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"5\" data-aria-level=\"1\"><a href=\"https:\/\/www.linkedin.com\/posts\/domtar_domtar175-nextisnow-activity-7138975575704051712-R6DW\" target=\"_blank\" rel=\"noopener\">LinkedIn : Domtar fait don de 100 000 $ en bourses d&rsquo;\u00e9tudes \u00e0 Clemson et \u00e0 l&rsquo;Universit\u00e9 de Sherbrooke<\/a><\/li>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"5\" data-list-defn-props=\"{\"335552541\":1,\"335559684\":-2,\"335559685\":720,\"335559991\":360,\"469769226\":\"Symbol\",\"469769242\":[8226],\"469777803\":\"left\",\"469777804\":\"\uf0b7\",\"469777815\":\"hybridMultilevel\"}\" aria-setsize=\"-1\" data-aria-posinset=\"5\" data-aria-level=\"1\"><a href=\"https:\/\/www.youtube.com\/watch?v=yBEcsmEbSlM\" target=\"_blank\" rel=\"noopener\"><span data-contrast=\"none\">Vid\u00e9o : Le changement est source d&rsquo;opportunit\u00e9s &#8211; L&rsquo;avenir, c&rsquo;est maintenant<\/span><\/a><span data-ccp-props=\"{\"201341983\":0,\"335559739\":0,\"335559740\":240}\"> <\/span><\/li>\n<\/ul>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n    <section id=\"immersive_panel_2\" class=\"lc-module section-video video-container full\">\n      <div class=\"lc-module-inner\">\n                <div class=\"video-wrapper lc-module-wrapper\">\n\n            <span class=\"intent-icon ion-ios-play\"><\/span>\n\n            \n            <div class=\"video-object\" data-source=\"https:\/\/youtu.be\/om5SF7zQzLs?si=rHep-KjCgBFP2rrB\">\n                <div class=\"embed-responsive embed-responsive-16by9 video-ratio\">\n                    <!-- Embed Begin -->\n                    <iframe style=\"position: absolute; left: 0px; top: 0px; width: 100%; height: 100%\" src=\"https:\/\/www.youtube.com\/embed\/om5SF7zQzLs?feature=oembed&amp;loop=1&amp;rel=0&amp;enablejsapi=1&amp;origin=https%3A%2F%2Flive-domtar-newsroom-2020.pantheonsite.io\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen=\"\" title=\"Vid\u00e9o du 175e anniversaire de Domtar avec sous-titres (FRAN\u00c7AIS)\"><\/iframe>                    <!-- Embed End -->\n                <\/div> \n            <\/div>\n\n        <\/div>\n                \n                                <button type=\"button\" class=\"btn btn-primary\" data-toggle=\"modal\" data-target=\"#video_transcript_immersive_panel_2\">  Transcription de la vid\u00e9o  <\/button>\n\n                        <div class=\"modal fade modal-transcript\" id=\"video_transcript_immersive_panel_2\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"modal_label_immersive_panel_2\" aria-hidden=\"true\">\n                <div class=\"modal-dialog modal-dialog-centered\" role=\"document\">\n                    <div class=\"modal-content\">\n                        <div class=\"modal-header\">\n                            <button type=\"button\" class=\"close\" data-dismiss=\"modal\" aria-label=\"Close\">\n                                <span aria-hidden=\"true\">\u00d7<\/span>\n                            <\/button>\n                            <h4 class=\"modal-title\" id=\"modal_label_immersive_panel_2\">Transcription de la vid\u00e9o<\/h4>\n                        <\/div>\n                        <div class=\"modal-body\">\n                            <p>Le changement est source d&rsquo;opportunit\u00e9s &#8211; aller de l&rsquo;avant avec un nouvel objectif, prosp\u00e9rer d&rsquo;une nouvelle mani\u00e8re. \u00c9largir ce qui est possible pour un avenir meilleur,<br> plus brillant. Personne ne le comprend mieux que Domtar.  <\/p>\n<p>Depuis 1848, nous r\u00e9inventons notre place et notre raison d&rsquo;\u00eatre dans le monde. Tout cela pour mieux fabriquer ce dont les gens ont le plus besoin. <br>  Le monde \u00e9volue en permanence, et nous \u00e9voluons avec lui pour nous adapter au moment pr\u00e9sent. Mais au cours des 175 derni\u00e8res ann\u00e9es, certaines choses sont rest\u00e9es constantes :<br>. <\/p>\n<p>Notre agilit\u00e9 et notre capacit\u00e9 d&rsquo;adaptation. L&rsquo;attention que nous portons aux autres et \u00e0 notre environnement. Notre esprit d&rsquo;innovation tenace. Ces valeurs ont toujours \u00e9t\u00e9 au c\u0153ur de nos principes directeurs (<br> ) et continuent d&rsquo;\u00eatre notre \u00e9toile polaire, qui veille \u00e0 ce que nous ne perdions jamais le nord.   <\/p>\n<p>Aujourd&rsquo;hui, nous nous consacrons \u00e0 la fabrication responsable de papier, de p\u00e2te \u00e0 papier et d&#8217;emballages, avec un engagement in\u00e9branlable en faveur de la protection de l&rsquo;environnement<br>. Nous fournissons des mat\u00e9riaux de qualit\u00e9 aux clients qui rendent possibles les produits de tous les jours, et nous nous soucions profond\u00e9ment de la r\u00e9ussite de<br> tous ceux avec qui nous nous associons en cours de route. <\/p>\n<p>Nous permettons \u00e0 nos employ\u00e9s de s&rsquo;\u00e9panouir, ce qui renforce nos communaut\u00e9s.<\/p>\n<p>C&rsquo;est un cycle en constante \u00e9volution qui a un impact positif sur le monde.<\/p>\n<p>C&rsquo;est ce qui se passe depuis 175 ans, et cela continuera aujourd&rsquo;hui et pour les g\u00e9n\u00e9rations \u00e0 venir.<\/p>\n<p>La suite, c&rsquo;est maintenant.<\/p>\n<p>Domtar<br> c\u00e9l\u00e8bre ses 175 ans<\/p>\n                        <\/div>\n                        <div class=\"modal-footer\">\n                            <button type=\"button\" class=\"btn btn-secondary\" data-dismiss=\"modal\">Fermer<\/button>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n\n                  \n      <\/div>\n    <\/section>\n\n","protected":false},"excerpt":{"rendered":"<p>Lorsque nous avons c\u00e9l\u00e9br\u00e9 le 175e anniversaire de Domtar, nous n&rsquo;avons pas seulement jet\u00e9 un regard sur le pass\u00e9. D\u00e9couvrez quelques jalons de notre histoire et apprenez comment ils serviront de base aux 175 prochaines ann\u00e9es. <\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_genesis_block_theme_hide_title":false,"footnotes":""},"categories":[975],"tags":[1112,1109,412,1110,1111,1091,1104],"class_list":["post-29439","post","type-post","status-publish","format-standard","hentry","category-our-company-fr","tag-anniversaire","tag-bourses-detudes-domtar","tag-durabilite","tag-history-fr","tag-le-prochain-est-le-present","tag-securite-de-la-fabrication-fr","tag-volontariat-et-engagement-communautaire","without-featured-image"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>L&#039;avenir, c&#039;est maintenant : C\u00e9l\u00e9bration du 175e anniversaire de Domtar et notre avenir<\/title>\n<meta name=\"description\" content=\"Cette ann\u00e9e, nous avons c\u00e9l\u00e9br\u00e9 le 175e anniversaire de Domtar. Mais nous ne nous contentons pas de jeter un regard sur le pass\u00e9 ; nous sommes \u00e9galement enthousiastes \u00e0 l&#039;\u00e9gard de l&#039;avenir. Lisez :\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.domtar.com\/fr\/lavenir-cest-maintenant-celebrons-le-175e-anniversaire-de-domtar-et-regardons-vers-lavenir\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;avenir, c&#039;est maintenant : C\u00e9l\u00e9brons le 175e anniversaire de Domtar et regardons vers l&#039;avenir\" \/>\n<meta property=\"og:description\" content=\"Cette ann\u00e9e, nous avons c\u00e9l\u00e9br\u00e9 le 175e anniversaire de Domtar. Mais nous ne nous contentons pas de jeter un regard sur le pass\u00e9 ; nous sommes \u00e9galement enthousiastes \u00e0 l&#039;\u00e9gard de l&#039;avenir. Lisez :\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.domtar.com\/fr\/lavenir-cest-maintenant-celebrons-le-175e-anniversaire-de-domtar-et-regardons-vers-lavenir\/\" \/>\n<meta property=\"og:site_name\" content=\"Domtar\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DomtarEveryday\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-22T09:51:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.domtar.com\/wp-content\/uploads\/2025\/10\/Domtar_sharing_img_2x-min-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2400\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Lauren.Hultz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@DomtarEveryday\" \/>\n<meta name=\"twitter:site\" content=\"@DomtarEveryday\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lauren.Hultz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.domtar.com\\\/fr\\\/lavenir-cest-maintenant-celebrons-le-175e-anniversaire-de-domtar-et-regardons-vers-lavenir\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.domtar.com\\\/fr\\\/lavenir-cest-maintenant-celebrons-le-175e-anniversaire-de-domtar-et-regardons-vers-lavenir\\\/\"},\"author\":{\"name\":\"Lauren.Hultz\",\"@id\":\"https:\\\/\\\/www.domtar.com\\\/fr\\\/#\\\/schema\\\/person\\\/163327fa725eb5b7bea579643fd8356e\"},\"headline\":\"L&rsquo;avenir, c&rsquo;est maintenant : C\u00e9l\u00e9brons le 175e anniversaire de Domtar et regardons vers l&rsquo;avenir\",\"datePublished\":\"2023-12-22T09:51:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.domtar.com\\\/fr\\\/lavenir-cest-maintenant-celebrons-le-175e-anniversaire-de-domtar-et-regardons-vers-lavenir\\\/\"},\"wordCount\":1056,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.domtar.com\\\/fr\\\/#organization\"},\"keywords\":[\"anniversaire\",\"bourses d'\u00e9tudes domtar\",\"Durabilit\u00e9\",\"History\",\"Le prochain est le pr\u00e9sent\",\"s\u00e9curit\u00e9 de la fabrication\",\"Volontariat et engagement communautaire\"],\"articleSection\":[\"Our Company\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.domtar.com\\\/fr\\\/lavenir-cest-maintenant-celebrons-le-175e-anniversaire-de-domtar-et-regardons-vers-lavenir\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.domtar.com\\\/fr\\\/lavenir-cest-maintenant-celebrons-le-175e-anniversaire-de-domtar-et-regardons-vers-lavenir\\\/\",\"url\":\"https:\\\/\\\/www.domtar.com\\\/fr\\\/lavenir-cest-maintenant-celebrons-le-175e-anniversaire-de-domtar-et-regardons-vers-lavenir\\\/\",\"name\":\"L'avenir, c'est maintenant : C\u00e9l\u00e9bration du 175e anniversaire de Domtar et notre avenir\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.domtar.com\\\/fr\\\/#website\"},\"datePublished\":\"2023-12-22T09:51:44+00:00\",\"description\":\"Cette ann\u00e9e, nous avons c\u00e9l\u00e9br\u00e9 le 175e anniversaire de Domtar. Mais nous ne nous contentons pas de jeter un regard sur le pass\u00e9 ; nous sommes \u00e9galement enthousiastes \u00e0 l'\u00e9gard de l'avenir. Lisez :\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.domtar.com\\\/fr\\\/lavenir-cest-maintenant-celebrons-le-175e-anniversaire-de-domtar-et-regardons-vers-lavenir\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.domtar.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.domtar.com\\\/fr\\\/\",\"name\":\"Domtar | The Fiber for the Future\",\"description\":\"The Sustainable Paper, Pulp and Packaging Company\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.domtar.com\\\/fr\\\/#organization\"},\"alternateName\":\"Domtar\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.domtar.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.domtar.com\\\/fr\\\/#organization\",\"name\":\"Domtar Corporation\",\"url\":\"https:\\\/\\\/www.domtar.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.domtar.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.domtar.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/domtar_logo_rgb_green.png\",\"contentUrl\":\"https:\\\/\\\/www.domtar.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/domtar_logo_rgb_green.png\",\"width\":1153,\"height\":263,\"caption\":\"Domtar\"},\"image\":{\"@id\":\"https:\\\/\\\/www.domtar.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/en.wikipedia.org\\\/wiki\\\/Domtar\",\"https:\\\/\\\/www.wikidata.org\\\/wiki\\\/Q1238739\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/domtar\",\"https:\\\/\\\/x.com\\\/DomtarEveryday\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCh8Zhq2Rmxhl5Km0krrGoYw\",\"https:\\\/\\\/www.instagram.com\\\/domtar_paper\\\/\",\"https:\\\/\\\/www.facebook.com\\\/DomtarEveryday\\\/\",\"https:\\\/\\\/www.crunchbase.com\\\/organization\\\/domtar\"],\"ethicsPolicy\":\"https:\\\/\\\/www.domtar.com\\\/fr\\\/notre-entreprise\\\/ethique-et-conformite\\\/\",\"legalName\":\"Domtar Corporation\",\"foundingDate\":\"1848\",\"description\":\"Privately held North American manufacturer of diversified forest products.\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":13000},\"address\":[{\"@type\":\"PostalAddress\",\"streetAddress\":\"234 Kingsley Park Drive\",\"addressLocality\":\"Fort Mill\",\"addressRegion\":\"SC\",\"postalCode\":\"29715\",\"addressCountry\":\"US\"},{\"@type\":\"PostalAddress\",\"streetAddress\":\"395 De Maisonneuve Blvd West\",\"addressLocality\":\"Montr\u00e9al\",\"addressRegion\":\"QC\",\"postalCode\":\"H3A 1L6\",\"addressCountry\":\"CA\"},{\"@type\":\"PostalAddress\",\"streetAddress\":\"2nd Floor, 3600 Lysander Lane\",\"addressLocality\":\"Richmond\",\"addressRegion\":\"BC\",\"postalCode\":\"V7B 1C3\",\"addressCountry\":\"CA\"}],\"award\":[\"SFI Leadership in Conservation Award (2026)\",\"Corporate Knights Private 25 Most Sustainable Corporations (2025)\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.domtar.com\\\/fr\\\/#\\\/schema\\\/person\\\/163327fa725eb5b7bea579643fd8356e\",\"name\":\"Lauren.Hultz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdd1b47f44190d37b4501eb0534c2c366d29145004c7ea14fdcba64e5eaf6ebc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdd1b47f44190d37b4501eb0534c2c366d29145004c7ea14fdcba64e5eaf6ebc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdd1b47f44190d37b4501eb0534c2c366d29145004c7ea14fdcba64e5eaf6ebc?s=96&d=mm&r=g\",\"caption\":\"Lauren.Hultz\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"L'avenir, c'est maintenant : C\u00e9l\u00e9bration du 175e anniversaire de Domtar et notre avenir","description":"Cette ann\u00e9e, nous avons c\u00e9l\u00e9br\u00e9 le 175e anniversaire de Domtar. Mais nous ne nous contentons pas de jeter un regard sur le pass\u00e9 ; nous sommes \u00e9galement enthousiastes \u00e0 l'\u00e9gard de l'avenir. Lisez :","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.domtar.com\/fr\/lavenir-cest-maintenant-celebrons-le-175e-anniversaire-de-domtar-et-regardons-vers-lavenir\/","og_locale":"fr_FR","og_type":"article","og_title":"L'avenir, c'est maintenant : C\u00e9l\u00e9brons le 175e anniversaire de Domtar et regardons vers l'avenir","og_description":"Cette ann\u00e9e, nous avons c\u00e9l\u00e9br\u00e9 le 175e anniversaire de Domtar. Mais nous ne nous contentons pas de jeter un regard sur le pass\u00e9 ; nous sommes \u00e9galement enthousiastes \u00e0 l'\u00e9gard de l'avenir. Lisez :","og_url":"https:\/\/www.domtar.com\/fr\/lavenir-cest-maintenant-celebrons-le-175e-anniversaire-de-domtar-et-regardons-vers-lavenir\/","og_site_name":"Domtar","article_publisher":"https:\/\/www.facebook.com\/DomtarEveryday\/","article_published_time":"2023-12-22T09:51:44+00:00","og_image":[{"width":2400,"height":1350,"url":"https:\/\/www.domtar.com\/wp-content\/uploads\/2025\/10\/Domtar_sharing_img_2x-min-1.png","type":"image\/png"}],"author":"Lauren.Hultz","twitter_card":"summary_large_image","twitter_creator":"@DomtarEveryday","twitter_site":"@DomtarEveryday","twitter_misc":{"\u00c9crit par":"Lauren.Hultz","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.domtar.com\/fr\/lavenir-cest-maintenant-celebrons-le-175e-anniversaire-de-domtar-et-regardons-vers-lavenir\/#article","isPartOf":{"@id":"https:\/\/www.domtar.com\/fr\/lavenir-cest-maintenant-celebrons-le-175e-anniversaire-de-domtar-et-regardons-vers-lavenir\/"},"author":{"name":"Lauren.Hultz","@id":"https:\/\/www.domtar.com\/fr\/#\/schema\/person\/163327fa725eb5b7bea579643fd8356e"},"headline":"L&rsquo;avenir, c&rsquo;est maintenant : C\u00e9l\u00e9brons le 175e anniversaire de Domtar et regardons vers l&rsquo;avenir","datePublished":"2023-12-22T09:51:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.domtar.com\/fr\/lavenir-cest-maintenant-celebrons-le-175e-anniversaire-de-domtar-et-regardons-vers-lavenir\/"},"wordCount":1056,"commentCount":0,"publisher":{"@id":"https:\/\/www.domtar.com\/fr\/#organization"},"keywords":["anniversaire","bourses d'\u00e9tudes domtar","Durabilit\u00e9","History","Le prochain est le pr\u00e9sent","s\u00e9curit\u00e9 de la fabrication","Volontariat et engagement communautaire"],"articleSection":["Our Company"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.domtar.com\/fr\/lavenir-cest-maintenant-celebrons-le-175e-anniversaire-de-domtar-et-regardons-vers-lavenir\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.domtar.com\/fr\/lavenir-cest-maintenant-celebrons-le-175e-anniversaire-de-domtar-et-regardons-vers-lavenir\/","url":"https:\/\/www.domtar.com\/fr\/lavenir-cest-maintenant-celebrons-le-175e-anniversaire-de-domtar-et-regardons-vers-lavenir\/","name":"L'avenir, c'est maintenant : C\u00e9l\u00e9bration du 175e anniversaire de Domtar et notre avenir","isPartOf":{"@id":"https:\/\/www.domtar.com\/fr\/#website"},"datePublished":"2023-12-22T09:51:44+00:00","description":"Cette ann\u00e9e, nous avons c\u00e9l\u00e9br\u00e9 le 175e anniversaire de Domtar. Mais nous ne nous contentons pas de jeter un regard sur le pass\u00e9 ; nous sommes \u00e9galement enthousiastes \u00e0 l'\u00e9gard de l'avenir. Lisez :","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.domtar.com\/fr\/lavenir-cest-maintenant-celebrons-le-175e-anniversaire-de-domtar-et-regardons-vers-lavenir\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.domtar.com\/fr\/#website","url":"https:\/\/www.domtar.com\/fr\/","name":"Domtar | The Fiber for the Future","description":"The Sustainable Paper, Pulp and Packaging Company","publisher":{"@id":"https:\/\/www.domtar.com\/fr\/#organization"},"alternateName":"Domtar","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.domtar.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.domtar.com\/fr\/#organization","name":"Domtar Corporation","url":"https:\/\/www.domtar.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.domtar.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.domtar.com\/wp-content\/uploads\/2023\/03\/domtar_logo_rgb_green.png","contentUrl":"https:\/\/www.domtar.com\/wp-content\/uploads\/2023\/03\/domtar_logo_rgb_green.png","width":1153,"height":263,"caption":"Domtar"},"image":{"@id":"https:\/\/www.domtar.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/en.wikipedia.org\/wiki\/Domtar","https:\/\/www.wikidata.org\/wiki\/Q1238739","https:\/\/www.linkedin.com\/company\/domtar","https:\/\/x.com\/DomtarEveryday","https:\/\/www.youtube.com\/channel\/UCh8Zhq2Rmxhl5Km0krrGoYw","https:\/\/www.instagram.com\/domtar_paper\/","https:\/\/www.facebook.com\/DomtarEveryday\/","https:\/\/www.crunchbase.com\/organization\/domtar"],"ethicsPolicy":"https:\/\/www.domtar.com\/fr\/notre-entreprise\/ethique-et-conformite\/","legalName":"Domtar Corporation","foundingDate":"1848","description":"Privately held North American manufacturer of diversified forest products.","numberOfEmployees":{"@type":"QuantitativeValue","minValue":13000},"address":[{"@type":"PostalAddress","streetAddress":"234 Kingsley Park Drive","addressLocality":"Fort Mill","addressRegion":"SC","postalCode":"29715","addressCountry":"US"},{"@type":"PostalAddress","streetAddress":"395 De Maisonneuve Blvd West","addressLocality":"Montr\u00e9al","addressRegion":"QC","postalCode":"H3A 1L6","addressCountry":"CA"},{"@type":"PostalAddress","streetAddress":"2nd Floor, 3600 Lysander Lane","addressLocality":"Richmond","addressRegion":"BC","postalCode":"V7B 1C3","addressCountry":"CA"}],"award":["SFI Leadership in Conservation Award (2026)","Corporate Knights Private 25 Most Sustainable Corporations (2025)"]},{"@type":"Person","@id":"https:\/\/www.domtar.com\/fr\/#\/schema\/person\/163327fa725eb5b7bea579643fd8356e","name":"Lauren.Hultz","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/fdd1b47f44190d37b4501eb0534c2c366d29145004c7ea14fdcba64e5eaf6ebc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fdd1b47f44190d37b4501eb0534c2c366d29145004c7ea14fdcba64e5eaf6ebc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fdd1b47f44190d37b4501eb0534c2c366d29145004c7ea14fdcba64e5eaf6ebc?s=96&d=mm&r=g","caption":"Lauren.Hultz"}}]}},"_links":{"self":[{"href":"https:\/\/www.domtar.com\/fr\/wp-json\/wp\/v2\/posts\/29439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.domtar.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.domtar.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.domtar.com\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.domtar.com\/fr\/wp-json\/wp\/v2\/comments?post=29439"}],"version-history":[{"count":0,"href":"https:\/\/www.domtar.com\/fr\/wp-json\/wp\/v2\/posts\/29439\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.domtar.com\/fr\/wp-json\/wp\/v2\/media?parent=29439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.domtar.com\/fr\/wp-json\/wp\/v2\/categories?post=29439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.domtar.com\/fr\/wp-json\/wp\/v2\/tags?post=29439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}