{"id":29316,"date":"2024-02-22T09:33:28","date_gmt":"2024-02-22T09:33:28","guid":{"rendered":"https:\/\/www.domtar.com\/les-ingenieurs-en-pates-et-papiers-faconnent-lavenir-de-notre-industrie-2\/"},"modified":"2025-10-23T22:09:00","modified_gmt":"2025-10-23T22:09:00","slug":"les-ingenieurs-en-pates-et-papiers-faconnent-lavenir-de-notre-industrie-2","status":"publish","type":"post","link":"https:\/\/www.domtar.com\/fr\/les-ingenieurs-en-pates-et-papiers-faconnent-lavenir-de-notre-industrie-2\/","title":{"rendered":"Les ing\u00e9nieurs en p\u00e2tes et papiers fa\u00e7onnent l&rsquo;avenir de notre industrie"},"content":{"rendered":"\r\n<p>Article en fran\u00e7ais (PDF)<\/p>\r\n\r\n\r\n\r\n<p>Les produits forestiers tels que la p\u00e2te \u00e0 papier, le papier et le bois d&rsquo;\u0153uvre contribuent \u00e0 fa\u00e7onner la vie quotidienne des gens dans le monde entier. Les ing\u00e9nieurs du secteur de la p\u00e2te et du papier contribuent \u00e0 fa\u00e7onner ces produits en am\u00e9liorant les projets et les processus qui stimulent l&rsquo;innovation dans notre entreprise et dans notre secteur d&rsquo;activit\u00e9.<\/p>\r\n\r\n\r\n\r\n<p>Dans le cadre de la Semaine des ing\u00e9nieurs, nous soulignons le travail de plusieurs ing\u00e9nieurs en p\u00e2tes et papiers du groupe d&rsquo;entreprises Paper Excellence : Domtar, R\u00e9solu et Paper Excellence Canada. Poursuivez votre lecture pour en savoir plus.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Les ing\u00e9nieurs en p\u00e2tes et papiers fa\u00e7onnent l&rsquo;avenir de nos usines<\/h2>\r\n\r\n\r\n\r\n<p>\u00c9tudiante en g\u00e9nie chimique, Melanie Howard esp\u00e9rait entamer une carri\u00e8re dans le secteur de la fabrication, mais elle n&rsquo;avait pas encore arr\u00eat\u00e9 son choix sur une industrie en particulier. Elle a d\u00e9croch\u00e9 un poste coop\u00e9ratif \u00e0 l&rsquo;usine Domtar de Hawesville, dans le Kentucky, et a d\u00e9couvert une industrie au potentiel illimit\u00e9.<\/p>\r\n\r\n\r\n\r\n<p>\u00ab\u00a0J&rsquo;ai \u00e9t\u00e9 \u00e9poustoufl\u00e9 par la complexit\u00e9 du processus et par le fait qu&rsquo;il est beaucoup plus complexe que je ne l&rsquo;aurais jamais imagin\u00e9. J&rsquo;ai saut\u00e9 sur l&rsquo;occasion de travailler ici \u00e0 plein temps\u00a0\u00bb, explique M. Howard. \u00ab\u00a0Aujourd&rsquo;hui, en tant qu&rsquo;ing\u00e9nieur en environnement, j&rsquo;aime diriger des projets d&rsquo;am\u00e9lioration des processus qui nous aident \u00e0 r\u00e9duire les d\u00e9chets et \u00e0 exploiter nos sous-produits de mani\u00e8re durable.\u00a0\u00bb<\/p>\r\n\r\n\r\n\r\n<p>John Edwards, surintendant des op\u00e9rations de l&rsquo;usine de Plymouth, a men\u00e9 des efforts pour r\u00e9duire la quantit\u00e9 d&rsquo;eau utilis\u00e9e dans le processus de fabrication de la p\u00e2te \u00e0 papier. Il repr\u00e9sente actuellement Domtar en tant que pr\u00e9sident du <a href=\"https:\/\/www.tappi.org\/members\/divisions--committees\/paper-and-board\/\" target=\"_blank\" rel=\"noreferrer noopener\">comit\u00e9 des technologies et des op\u00e9rations de fabrication du papier de<\/a> TAPPI. En 2020, son engagement \u00e0 avoir un impact positif sur les gens par le biais de son travail lui a valu d&rsquo;\u00eatre nomm\u00e9 <a href=\"https:\/\/yp.tappi.org\/content\/member-spotlight\/tappi-yp-spotlight-john-edwards\/\" target=\"_blank\" rel=\"noreferrer noopener\">jeune professionnel de l&rsquo;ann\u00e9e<\/a> par TAPPI.<\/p>\r\n\r\n\r\n\r\n<p>Il investit \u00e9galement dans l&rsquo;avenir de sa profession en soutenant les efforts de recrutement, en s&rsquo;associant \u00e0 l&rsquo;association foresti\u00e8re de Caroline du Nord pour expliquer <a href=\"https:\/\/youtu.be\/9yu1XHAl3lw?si=HyhZHrkcOLawcgTD\" target=\"_blank\" rel=\"noreferrer noopener\">comment la p\u00e2te en flocons est fabriqu\u00e9e<\/a> \u00e0 partir de fibres de bois durables, et en prenant la parole lors du r\u00e9cent sommet des \u00e9tudiants de TAPPI.<\/p>\r\n\r\n\r\n\r\n<p>Chez Produits forestiers R\u00e9solu, Vanessa Simard applique les technologies \u00e9mergentes pour soutenir la transformation num\u00e9rique de l&rsquo;industrie des produits forestiers. En tant qu&rsquo;ing\u00e9nieure industrielle et superviseure de la planification et de l&rsquo;optimisation de la production aux op\u00e9rations du Saguenay-Lac-Saint-Jean (Qu\u00e9bec), elle a aid\u00e9 l&rsquo;entreprise \u00e0 utiliser l&rsquo;intelligence artificielle pour am\u00e9liorer l&rsquo;efficacit\u00e9 de la fabrication.<\/p>\r\n\r\n\r\n\r\n<p>L&rsquo;expertise de Mme Simard en mati\u00e8re d&rsquo;IA l&rsquo;a amen\u00e9e \u00e0 d\u00e9velopper une solution prim\u00e9e bas\u00e9e sur l&rsquo;IA qui r\u00e9duit consid\u00e9rablement le temps de planification du processus de s\u00e9chage du bois d&rsquo;\u0153uvre. Cette solution a depuis \u00e9t\u00e9 d\u00e9ploy\u00e9e dans plusieurs installations de R\u00e9solu.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Les ing\u00e9nieurs en formation (IET) fa\u00e7onnent leur carri\u00e8re et contribuent \u00e0 la r\u00e9ussite de l&rsquo;industrie<\/h2>\r\n\r\n\r\n\r\n<p>Paper Excellence Canada s\u00e9lectionne chaque ann\u00e9e de r\u00e9cents dipl\u00f4m\u00e9s en ing\u00e9nierie pour leur programme d&rsquo;ing\u00e9nieur en formation (EIT). Ce programme rotatif de 18 mois permet aux ing\u00e9nieurs en p\u00e2tes et papiers \u00e9mergents de d\u00e9marrer solidement leur carri\u00e8re et de se positionner en vue d&rsquo;une r\u00e9ussite future.<\/p>\r\n\r\n\r\n\r\n<p>Les IET apportent une contribution importante au secteur d\u00e8s le premier jour.<\/p>\r\n\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n<li>\u00c0 Meadow Lake Pulp, Attila Szanto, ing\u00e9nieur stagiaire, applique ses connaissances en g\u00e9nie chimique dans le cadre d&rsquo;un essai anti-calcaire sur les \u00e9vaporateurs de l&rsquo;usine.<\/li>\r\n\r\n\r\n\r\n<li>Nawaf Salem, EIT \u00e0 l&rsquo;usine de Skookumchuck, met \u00e0 profit sa passion pour le d\u00e9veloppement durable afin de r\u00e9duire l&rsquo;impact de l&rsquo;usine sur l&rsquo;environnement.<\/li>\r\n\r\n\r\n\r\n<li>\u00c0 Howe Sound, l&rsquo;IET Asad Hayat travaille sur un projet visant \u00e0 optimiser l&rsquo;utilisation des copeaux de bois et \u00e0 r\u00e9duire les d\u00e9chets.<\/li>\r\n<\/ul>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Nous fa\u00e7onnons l&rsquo;avenir en soutenant les \u00e9tudiants en ing\u00e9nierie<\/h2>\r\n\r\n\r\n\r\n<p>Chaque ann\u00e9e, nous recrutons des <a href=\"https:\/\/newsroom.domtar.com\/domtar-internships-national-intern-day\/\">stagiaires en ing\u00e9nierie et des \u00e9tudiants en alternance<\/a>dans diverses disciplines, ce qui leur permet d&rsquo;acqu\u00e9rir une exp\u00e9rience concr\u00e8te et d&rsquo;avoir un impact sur nos activit\u00e9s. L&rsquo;autonomisation des \u00e9tudiants en ing\u00e9nierie est essentielle pour former la prochaine g\u00e9n\u00e9ration d&rsquo;ing\u00e9nieurs qui continueront \u00e0 innover au sein de l&rsquo;industrie des produits forestiers. Paper Excellence, qui appartient \u00e0 Jackson Wijaya, homme d&rsquo;affaires et investisseur influent, soutient cette initiative.<\/p>\r\n\r\n\r\n\r\n<p>\u00ab\u00a0D\u00e8s le premier jour, nos stagiaires et \u00e9tudiants en alternance participent \u00e0 des projets li\u00e9s \u00e0 la qualit\u00e9, \u00e0 l&rsquo;optimisation, \u00e0 l&rsquo;am\u00e9lioration continue, \u00e0 la r\u00e9duction des co\u00fbts et aux pratiques environnementales &#8211; des initiatives qui peuvent permettre \u00e0 l&rsquo;entreprise d&rsquo;\u00e9conomiser des millions de dollars\u00a0\u00bb, explique Talia Massey, qui g\u00e8re le programme de talents en d\u00e9but de carri\u00e8re de Domtar.<\/p>\r\n\r\n\r\n\r\n<p>Nous sommes \u00e9galement partenaires de la North Carolina State University, de l&rsquo;University of Wisconsin- Stevens Point et de l&rsquo;Universit\u00e9 Laval, entre autres, pour l&rsquo;octroi de bourses d&rsquo;\u00e9tudes et de subventions de projets aux \u00e9tudiants d\u00e9sireux de devenir ing\u00e9nieurs en p\u00e2tes et papiers.<\/p>\r\n\r\n\r\n\r\n<p>Paper Excellence Canada a cr\u00e9\u00e9 un fonds de r\u00e9compense \u00e0 l&rsquo;Universit\u00e9 de l&rsquo;\u00eele de Vancouver pour soutenir les dipl\u00f4m\u00e9s des programmes de m\u00e9tiers et de technologie appliqu\u00e9e, tels que les programmes d&rsquo;ing\u00e9nierie \u00e9nerg\u00e9tique et d&rsquo;op\u00e9rateur de processus de l&rsquo;universit\u00e9.<\/p>\r\n\r\n\r\n\r\n<p>R\u00e9solu offre de nombreuses bourses et subventions aux ing\u00e9nieurs du secteur des p\u00e2tes et papiers, notamment une <a href=\"https:\/\/www.resolutefp.com\/Sustainability\/Conservation_and_Biodiversity\/Research_Partnerships\/\" target=\"_blank\" rel=\"noreferrer noopener\">subvention de recherche annuelle de 70 000 dollars canadiens<\/a> qui r\u00e9unit des sp\u00e9cialistes du g\u00e9nie forestier, du g\u00e9nie industriel, du g\u00e9nie m\u00e9canique et des technologies de l&rsquo;information.<\/p>\r\n\r\n\r\n\r\n<p>Qu&rsquo;il s&rsquo;agisse de m\u00e9canique, d&rsquo;\u00e9lectricit\u00e9, de chimie ou de <a href=\"https:\/\/newsroom.domtar.com\/domtar-engineering-careers\/\">g\u00e9nie<\/a> civil, les <a href=\"https:\/\/newsroom.domtar.com\/domtar-engineering-careers\/\">professionnels de l&rsquo;ing\u00e9nierie des<\/a> p\u00e2tes et papiers r\u00e9solvent des probl\u00e8mes et con\u00e7oivent des solutions qui produisent des avantages \u00e0 long terme qui fa\u00e7onnent notre avenir.<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\">En savoir plus<\/h3>\r\n\r\n\r\n\r\n<p>Si vous souhaitez contribuer \u00e0 fa\u00e7onner l&rsquo;avenir de l&rsquo;industrie des produits forestiers, consultez nos postes d&rsquo;ing\u00e9nieurs et nos stages sur l&rsquo;un de nos sites de carri\u00e8re :<\/p>\r\n\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n<li><a href=\"https:\/\/recruiting.ultipro.ca\/PAP5000PXCH\/JobBoard\/8842b9ae-4468-46fc-9458-64379cfc2c77\/?q=&amp;o=postedDateDesc&amp;w=&amp;wc=&amp;we=&amp;wpst=\" target=\"_blank\" rel=\"noreferrer noopener\">Site de carri\u00e8re de Paper Excellence<\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/jobs.jobvite.com\/domtar\" target=\"_blank\" rel=\"noreferrer noopener\">Domtar.com\/carri\u00e8res<\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/jobs.resolutefp.com\/?locale=en_US\" target=\"_blank\" rel=\"noreferrer noopener\">Site carri\u00e8re de R\u00e9solu<\/a><\/li>\r\n<\/ul>\r\n\r\n\r\n\r\n<p>&nbsp;<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Article en fran\u00e7ais (PDF) Les produits forestiers tels que la p\u00e2te \u00e0 papier, le papier et le bois d&rsquo;\u0153uvre contribuent \u00e0 fa\u00e7onner la vie quotidienne des gens dans le monde entier. Les ing\u00e9nieurs du secteur de la p\u00e2te et du papier contribuent \u00e0 fa\u00e7onner ces produits en am\u00e9liorant les projets et les processus qui stimulent &hellip;<\/p>\n","protected":false},"author":1,"featured_media":39483,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_genesis_block_theme_hide_title":false,"footnotes":""},"categories":[975],"tags":[1044],"class_list":{"0":"post-29316","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","6":"hentry","7":"category-our-company-fr","8":"tag-en-vedette","10":"with-featured-image"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Les ing\u00e9nieurs en p\u00e2tes et papiers fa\u00e7onnent l&#039;avenir de notre industrie - Domtar<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.domtar.com\/fr\/les-ingenieurs-en-pates-et-papiers-faconnent-lavenir-de-notre-industrie-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les ing\u00e9nieurs en p\u00e2tes et papiers fa\u00e7onnent l&#039;avenir de notre industrie\" \/>\n<meta property=\"og:description\" content=\"Article en fran\u00e7ais (PDF) Les produits forestiers tels que la p\u00e2te \u00e0 papier, le papier et le bois d&rsquo;\u0153uvre contribuent \u00e0 fa\u00e7onner la vie quotidienne des gens dans le monde entier. Les ing\u00e9nieurs du secteur de la p\u00e2te et du papier contribuent \u00e0 fa\u00e7onner ces produits en am\u00e9liorant les projets et les processus qui stimulent &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.domtar.com\/fr\/les-ingenieurs-en-pates-et-papiers-faconnent-lavenir-de-notre-industrie-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Domtar\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DomtarEveryday\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-22T09:33:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-23T22:09:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.domtar.com\/wp-content\/uploads\/2024\/02\/IMG_Newsroom_Engineer-Week_2024-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"855\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"domtarcom\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@DomtarEveryday\" \/>\n<meta name=\"twitter:site\" content=\"@DomtarEveryday\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"domtarcom\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.domtar.com\\\/fr\\\/les-ingenieurs-en-pates-et-papiers-faconnent-lavenir-de-notre-industrie-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.domtar.com\\\/fr\\\/les-ingenieurs-en-pates-et-papiers-faconnent-lavenir-de-notre-industrie-2\\\/\"},\"author\":{\"name\":\"domtarcom\",\"@id\":\"https:\\\/\\\/www.domtar.com\\\/fr\\\/#\\\/schema\\\/person\\\/1eceda201e008fe717760290e7efa36e\"},\"headline\":\"Les ing\u00e9nieurs en p\u00e2tes et papiers fa\u00e7onnent l&rsquo;avenir de notre industrie\",\"datePublished\":\"2024-02-22T09:33:28+00:00\",\"dateModified\":\"2025-10-23T22:09:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.domtar.com\\\/fr\\\/les-ingenieurs-en-pates-et-papiers-faconnent-lavenir-de-notre-industrie-2\\\/\"},\"wordCount\":1129,\"publisher\":{\"@id\":\"https:\\\/\\\/www.domtar.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.domtar.com\\\/fr\\\/les-ingenieurs-en-pates-et-papiers-faconnent-lavenir-de-notre-industrie-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.domtar.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/IMG_Newsroom_Engineer-Week_2024-3.jpg\",\"keywords\":[\"En vedette\"],\"articleSection\":[\"Our Company\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.domtar.com\\\/fr\\\/les-ingenieurs-en-pates-et-papiers-faconnent-lavenir-de-notre-industrie-2\\\/\",\"url\":\"https:\\\/\\\/www.domtar.com\\\/fr\\\/les-ingenieurs-en-pates-et-papiers-faconnent-lavenir-de-notre-industrie-2\\\/\",\"name\":\"Les ing\u00e9nieurs en p\u00e2tes et papiers fa\u00e7onnent l'avenir de notre industrie - Domtar\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.domtar.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.domtar.com\\\/fr\\\/les-ingenieurs-en-pates-et-papiers-faconnent-lavenir-de-notre-industrie-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.domtar.com\\\/fr\\\/les-ingenieurs-en-pates-et-papiers-faconnent-lavenir-de-notre-industrie-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.domtar.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/IMG_Newsroom_Engineer-Week_2024-3.jpg\",\"datePublished\":\"2024-02-22T09:33:28+00:00\",\"dateModified\":\"2025-10-23T22:09:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.domtar.com\\\/fr\\\/les-ingenieurs-en-pates-et-papiers-faconnent-lavenir-de-notre-industrie-2\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.domtar.com\\\/fr\\\/les-ingenieurs-en-pates-et-papiers-faconnent-lavenir-de-notre-industrie-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.domtar.com\\\/fr\\\/les-ingenieurs-en-pates-et-papiers-faconnent-lavenir-de-notre-industrie-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.domtar.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/IMG_Newsroom_Engineer-Week_2024-3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.domtar.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/IMG_Newsroom_Engineer-Week_2024-3.jpg\",\"width\":855,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.domtar.com\\\/fr\\\/les-ingenieurs-en-pates-et-papiers-faconnent-lavenir-de-notre-industrie-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.domtar.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les ing\u00e9nieurs en p\u00e2tes et papiers fa\u00e7onnent l&#8217;avenir de notre industrie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.domtar.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.domtar.com\\\/fr\\\/\",\"name\":\"Domtar | The Fiber for the Future\",\"description\":\"The Sustainable Paper, Pulp and Packaging Company\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.domtar.com\\\/fr\\\/#organization\"},\"alternateName\":\"Domtar\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.domtar.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.domtar.com\\\/fr\\\/#organization\",\"name\":\"Domtar\",\"url\":\"https:\\\/\\\/www.domtar.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.domtar.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.domtar.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/domtar_logo_rgb_green.png\",\"contentUrl\":\"https:\\\/\\\/www.domtar.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/domtar_logo_rgb_green.png\",\"width\":1153,\"height\":263,\"caption\":\"Domtar\"},\"image\":{\"@id\":\"https:\\\/\\\/www.domtar.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DomtarEveryday\\\/\",\"https:\\\/\\\/x.com\\\/DomtarEveryday\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/domtar\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCh8Zhq2Rmxhl5Km0krrGoYw\"],\"ethicsPolicy\":\"https:\\\/\\\/www.domtar.com\\\/fr\\\/notre-entreprise\\\/ethique-et-conformite\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.domtar.com\\\/fr\\\/#\\\/schema\\\/person\\\/1eceda201e008fe717760290e7efa36e\",\"name\":\"domtarcom\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6a4ce9fede2abd183940f0fdc0562cee7a1a11070fe70dcb01d2f164b0fde389?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6a4ce9fede2abd183940f0fdc0562cee7a1a11070fe70dcb01d2f164b0fde389?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6a4ce9fede2abd183940f0fdc0562cee7a1a11070fe70dcb01d2f164b0fde389?s=96&d=mm&r=g\",\"caption\":\"domtarcom\"},\"sameAs\":[\"https:\\\/\\\/domtarwpe.wpengine.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Les ing\u00e9nieurs en p\u00e2tes et papiers fa\u00e7onnent l'avenir de notre industrie - Domtar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.domtar.com\/fr\/les-ingenieurs-en-pates-et-papiers-faconnent-lavenir-de-notre-industrie-2\/","og_locale":"fr_FR","og_type":"article","og_title":"Les ing\u00e9nieurs en p\u00e2tes et papiers fa\u00e7onnent l'avenir de notre industrie","og_description":"Article en fran\u00e7ais (PDF) Les produits forestiers tels que la p\u00e2te \u00e0 papier, le papier et le bois d&rsquo;\u0153uvre contribuent \u00e0 fa\u00e7onner la vie quotidienne des gens dans le monde entier. Les ing\u00e9nieurs du secteur de la p\u00e2te et du papier contribuent \u00e0 fa\u00e7onner ces produits en am\u00e9liorant les projets et les processus qui stimulent &hellip;","og_url":"https:\/\/www.domtar.com\/fr\/les-ingenieurs-en-pates-et-papiers-faconnent-lavenir-de-notre-industrie-2\/","og_site_name":"Domtar","article_publisher":"https:\/\/www.facebook.com\/DomtarEveryday\/","article_published_time":"2024-02-22T09:33:28+00:00","article_modified_time":"2025-10-23T22:09:00+00:00","og_image":[{"width":855,"height":640,"url":"https:\/\/www.domtar.com\/wp-content\/uploads\/2024\/02\/IMG_Newsroom_Engineer-Week_2024-3.jpg","type":"image\/jpeg"}],"author":"domtarcom","twitter_card":"summary_large_image","twitter_creator":"@DomtarEveryday","twitter_site":"@DomtarEveryday","twitter_misc":{"\u00c9crit par":"domtarcom","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.domtar.com\/fr\/les-ingenieurs-en-pates-et-papiers-faconnent-lavenir-de-notre-industrie-2\/#article","isPartOf":{"@id":"https:\/\/www.domtar.com\/fr\/les-ingenieurs-en-pates-et-papiers-faconnent-lavenir-de-notre-industrie-2\/"},"author":{"name":"domtarcom","@id":"https:\/\/www.domtar.com\/fr\/#\/schema\/person\/1eceda201e008fe717760290e7efa36e"},"headline":"Les ing\u00e9nieurs en p\u00e2tes et papiers fa\u00e7onnent l&rsquo;avenir de notre industrie","datePublished":"2024-02-22T09:33:28+00:00","dateModified":"2025-10-23T22:09:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.domtar.com\/fr\/les-ingenieurs-en-pates-et-papiers-faconnent-lavenir-de-notre-industrie-2\/"},"wordCount":1129,"publisher":{"@id":"https:\/\/www.domtar.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.domtar.com\/fr\/les-ingenieurs-en-pates-et-papiers-faconnent-lavenir-de-notre-industrie-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.domtar.com\/wp-content\/uploads\/2024\/02\/IMG_Newsroom_Engineer-Week_2024-3.jpg","keywords":["En vedette"],"articleSection":["Our Company"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.domtar.com\/fr\/les-ingenieurs-en-pates-et-papiers-faconnent-lavenir-de-notre-industrie-2\/","url":"https:\/\/www.domtar.com\/fr\/les-ingenieurs-en-pates-et-papiers-faconnent-lavenir-de-notre-industrie-2\/","name":"Les ing\u00e9nieurs en p\u00e2tes et papiers fa\u00e7onnent l'avenir de notre industrie - Domtar","isPartOf":{"@id":"https:\/\/www.domtar.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.domtar.com\/fr\/les-ingenieurs-en-pates-et-papiers-faconnent-lavenir-de-notre-industrie-2\/#primaryimage"},"image":{"@id":"https:\/\/www.domtar.com\/fr\/les-ingenieurs-en-pates-et-papiers-faconnent-lavenir-de-notre-industrie-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.domtar.com\/wp-content\/uploads\/2024\/02\/IMG_Newsroom_Engineer-Week_2024-3.jpg","datePublished":"2024-02-22T09:33:28+00:00","dateModified":"2025-10-23T22:09:00+00:00","breadcrumb":{"@id":"https:\/\/www.domtar.com\/fr\/les-ingenieurs-en-pates-et-papiers-faconnent-lavenir-de-notre-industrie-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.domtar.com\/fr\/les-ingenieurs-en-pates-et-papiers-faconnent-lavenir-de-notre-industrie-2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.domtar.com\/fr\/les-ingenieurs-en-pates-et-papiers-faconnent-lavenir-de-notre-industrie-2\/#primaryimage","url":"https:\/\/www.domtar.com\/wp-content\/uploads\/2024\/02\/IMG_Newsroom_Engineer-Week_2024-3.jpg","contentUrl":"https:\/\/www.domtar.com\/wp-content\/uploads\/2024\/02\/IMG_Newsroom_Engineer-Week_2024-3.jpg","width":855,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.domtar.com\/fr\/les-ingenieurs-en-pates-et-papiers-faconnent-lavenir-de-notre-industrie-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.domtar.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Les ing\u00e9nieurs en p\u00e2tes et papiers fa\u00e7onnent l&#8217;avenir de notre industrie"}]},{"@type":"WebSite","@id":"https:\/\/www.domtar.com\/fr\/#website","url":"https:\/\/www.domtar.com\/fr\/","name":"Domtar | The Fiber for the Future","description":"The Sustainable Paper, Pulp and Packaging Company","publisher":{"@id":"https:\/\/www.domtar.com\/fr\/#organization"},"alternateName":"Domtar","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.domtar.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.domtar.com\/fr\/#organization","name":"Domtar","url":"https:\/\/www.domtar.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.domtar.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.domtar.com\/wp-content\/uploads\/2023\/03\/domtar_logo_rgb_green.png","contentUrl":"https:\/\/www.domtar.com\/wp-content\/uploads\/2023\/03\/domtar_logo_rgb_green.png","width":1153,"height":263,"caption":"Domtar"},"image":{"@id":"https:\/\/www.domtar.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DomtarEveryday\/","https:\/\/x.com\/DomtarEveryday","https:\/\/www.linkedin.com\/company\/domtar\/","https:\/\/www.youtube.com\/channel\/UCh8Zhq2Rmxhl5Km0krrGoYw"],"ethicsPolicy":"https:\/\/www.domtar.com\/fr\/notre-entreprise\/ethique-et-conformite\/"},{"@type":"Person","@id":"https:\/\/www.domtar.com\/fr\/#\/schema\/person\/1eceda201e008fe717760290e7efa36e","name":"domtarcom","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/6a4ce9fede2abd183940f0fdc0562cee7a1a11070fe70dcb01d2f164b0fde389?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6a4ce9fede2abd183940f0fdc0562cee7a1a11070fe70dcb01d2f164b0fde389?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6a4ce9fede2abd183940f0fdc0562cee7a1a11070fe70dcb01d2f164b0fde389?s=96&d=mm&r=g","caption":"domtarcom"},"sameAs":["https:\/\/domtarwpe.wpengine.com"]}]}},"_links":{"self":[{"href":"https:\/\/www.domtar.com\/fr\/wp-json\/wp\/v2\/posts\/29316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.domtar.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.domtar.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.domtar.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.domtar.com\/fr\/wp-json\/wp\/v2\/comments?post=29316"}],"version-history":[{"count":0,"href":"https:\/\/www.domtar.com\/fr\/wp-json\/wp\/v2\/posts\/29316\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.domtar.com\/fr\/wp-json\/wp\/v2\/media\/39483"}],"wp:attachment":[{"href":"https:\/\/www.domtar.com\/fr\/wp-json\/wp\/v2\/media?parent=29316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.domtar.com\/fr\/wp-json\/wp\/v2\/categories?post=29316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.domtar.com\/fr\/wp-json\/wp\/v2\/tags?post=29316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}